{"id":6461,"date":"2024-09-12T17:15:33","date_gmt":"2024-09-12T21:15:33","guid":{"rendered":"https:\/\/www.apls.ca\/?p=6461"},"modified":"2024-09-12T17:15:36","modified_gmt":"2024-09-12T21:15:36","slug":"une-centaine-dentreprises-de-la-petite-nation-sopposent-au-projet-la-loutre","status":"publish","type":"post","link":"https:\/\/www.apls.ca\/en\/archives\/6461","title":{"rendered":"Une centaine d\u2019entreprises de la Petite-Nation s\u2019opposent au projet La Loutre"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.apls.ca\/wp-content\/uploads\/2024\/08\/457383495_919489946880501_5605002302607743227_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.apls.ca\/wp-content\/uploads\/2024\/08\/457383495_919489946880501_5605002302607743227_n-1024x576.jpg\" alt=\"\" class=\"wp-image-6448\" srcset=\"https:\/\/www.apls.ca\/wp-content\/uploads\/2024\/08\/457383495_919489946880501_5605002302607743227_n-1024x576.jpg 1024w, https:\/\/www.apls.ca\/wp-content\/uploads\/2024\/08\/457383495_919489946880501_5605002302607743227_n-300x169.jpg 300w, https:\/\/www.apls.ca\/wp-content\/uploads\/2024\/08\/457383495_919489946880501_5605002302607743227_n-768x432.jpg 768w, https:\/\/www.apls.ca\/wp-content\/uploads\/2024\/08\/457383495_919489946880501_5605002302607743227_n.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Une centaine d\u2019entreprises de la Petite-Nation, en Outaouais, unissent leurs voix pour s\u2019opposer publiquement au <strong>projet de mine de graphite La Loutre<\/strong> de l\u2019entreprise <strong>Lomiko\u00a0Metals<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le groupe rassemble des travailleurs autonomes et des repr\u00e9sentants de petites et grandes entreprises, venant d\u2019une vari\u00e9t\u00e9 de domaines d\u2019emploi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019une des instigatrices de ce regroupement des\u00a0<q><strong>Gens d\u2019affaires de la Petite-Nation contre le projet minier La Loutre<\/strong><\/q>, <strong>Genevi\u00e8ve Gagnon<\/strong>, est entre autres propri\u00e9taire d\u2019une quincaillerie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab <em><strong>Parce qu'on est tous conscients que notre \u00e9cosyst\u00e8me \u00e9conomique est notamment bas\u00e9 \u2013 en grande partie bas\u00e9 \u2013 sur le tourisme, la vill\u00e9giature et la nature<\/strong><\/em> \u00bb, explique-t-elle en entrevue \u00e0 l\u2019\u00e9mission Les matins d\u2019ici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle affirme que le mouvement d\u2019opposition de la part du milieu des affaires au projet La Loutre a su rallier \u00ab en moins de deux semaines [...] plus de 100 entreprises repr\u00e9sent\u00e9es par plus de 115 gens d\u2019affaires de la r\u00e9gion. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab <em><strong>Pour nous, \u00e7a va de soi qu\u2019un projet comme celui-l\u00e0 va totalement \u00e0 l\u2019encontre de la stabilit\u00e9, la p\u00e9rennit\u00e9 \u00e9conomique, la vitalit\u00e9 \u00e9conomique de notre r\u00e9gion<\/strong><\/em> \u00bb, soutient-elle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/ici.radio-canada.ca\/nouvelle\/2103896\/opposition-entreprises-mine-lomiko-metals\">Lire la suite dans Radio Canada<\/a> !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une centaine d\u2019entreprises de la Petite-Nation, en Outaouais, unissent leurs voix pour s\u2019opposer publiquement au projet de mine de graphite La Loutre de l\u2019entreprise Lomiko\u00a0Metals. Le groupe rassemble des travailleurs autonomes et des repr\u00e9sentants de petites et grandes entreprises, venant &hellip; <a href=\"https:\/\/www.apls.ca\/en\/archives\/6461\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":73,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6461","post","type-post","status-publish","format-standard","hentry","category-sans-categorie"],"_links":{"self":[{"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/posts\/6461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/comments?post=6461"}],"version-history":[{"count":2,"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/posts\/6461\/revisions"}],"predecessor-version":[{"id":6463,"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/posts\/6461\/revisions\/6463"}],"wp:attachment":[{"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/media?parent=6461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/categories?post=6461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apls.ca\/en\/wp-json\/wp\/v2\/tags?post=6461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}